{"id":14910,"date":"2024-11-12T13:15:00","date_gmt":"2024-11-12T12:15:00","guid":{"rendered":"https:\/\/pre.auditoriumpalma.com\/es\/espectaculo\/medina-azahara\/"},"modified":"2024-11-12T13:15:00","modified_gmt":"2024-11-12T12:15:00","slug":"medina-azahara","status":"publish","type":"show","link":"https:\/\/auditoriumpalma.com\/en\/espectaculo\/medina-azahara\/","title":{"rendered":"MEDINA AZAHARA"},"content":{"rendered":"<p>En 2025\/2026 <b>Medina Azahara<\/b> se despedir\u00e1 definitivamente de los escenarios, poniendo fin a una carrera legendaria que ha marcado el rock andaluz durante m\u00e1s de cuatro d\u00e9cadas. Con un \u00faltimo tour cargado de emoci\u00f3n, titulado \u00ab<b><i>Todo Tiene Su Fin<\/i><\/b>\u00bb, el grupo se<br \/>prepara para ofrecer a sus seguidores un adi\u00f3s inolvidable. Esta gira ser\u00e1 un homenaje a todos los que los han acompa\u00f1ado desde sus inicios, recorriendo los grandes \u00e9xitos que han forjado su historia. <\/p>\n<p><b>Medina Azahara<\/b> cierra as\u00ed un ciclo, dejando una huella imborrable en la m\u00fasica espa\u00f1ola y en el coraz\u00f3n de su fiel p\u00fablico.<\/p>\n<p>Duraci\u00f3n aproximada: 2 horas<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/auditoriumpalma.com\/img\/logosEspectaculo\/PMR_BM_BC.png\" title=\"Image: https:\/\/auditoriumpalma.com\/img\/logosEspectaculo\/PMR_BM_BC.png\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 2025\/2026 Medina Azahara se despedir\u00e1 definitivamente de los escenarios, poniendo fin a una carrera legendaria que ha marcado el rock andaluz durante m\u00e1s de cuatro d\u00e9cadas. Con un \u00faltimo tour cargado de emoci\u00f3n, titulado \u00abTodo Tiene Su Fin\u00bb, el grupo seprepara para ofrecer a sus seguidores un adi\u00f3s inolvidable. Esta gira ser\u00e1 un homenaje&hellip;&nbsp;<a href=\"https:\/\/auditoriumpalma.com\/en\/espectaculo\/medina-azahara\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">MEDINA AZAHARA<\/span><\/a><\/p>\n","protected":false},"featured_media":14911,"template":"","meta":{"_acf_changed":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"genero":[48],"sala":[32],"company":[],"class_list":["post-14910","show","type-show","status-publish","has-post-thumbnail","hentry","genero-concierto-de-rock","sala-magna"],"acf":[],"_links":{"self":[{"href":"https:\/\/auditoriumpalma.com\/en\/wp-json\/wp\/v2\/show\/14910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auditoriumpalma.com\/en\/wp-json\/wp\/v2\/show"}],"about":[{"href":"https:\/\/auditoriumpalma.com\/en\/wp-json\/wp\/v2\/types\/show"}],"version-history":[{"count":0,"href":"https:\/\/auditoriumpalma.com\/en\/wp-json\/wp\/v2\/show\/14910\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auditoriumpalma.com\/en\/wp-json\/wp\/v2\/media\/14911"}],"wp:attachment":[{"href":"https:\/\/auditoriumpalma.com\/en\/wp-json\/wp\/v2\/media?parent=14910"}],"wp:term":[{"taxonomy":"genero","embeddable":true,"href":"https:\/\/auditoriumpalma.com\/en\/wp-json\/wp\/v2\/genero?post=14910"},{"taxonomy":"sala","embeddable":true,"href":"https:\/\/auditoriumpalma.com\/en\/wp-json\/wp\/v2\/sala?post=14910"},{"taxonomy":"company","embeddable":true,"href":"https:\/\/auditoriumpalma.com\/en\/wp-json\/wp\/v2\/company?post=14910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}